{"id":136,"count":12,"description":"","link":"https:\/\/3kubik.com\/en\/project_category\/collaboration\/","name":"Collaboration","slug":"collaboration","taxonomy":"project_category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Collaboration Archive - 3kubik GmbH<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Collaboration Archive\" \/>\n<meta property=\"og:url\" content=\"https:\/\/3kubik.com\/en\/project_category\/collaboration\/\" \/>\n<meta property=\"og:site_name\" content=\"3kubik GmbH\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/3kubik.com\\\/en\\\/project_category\\\/collaboration\\\/\",\"url\":\"https:\\\/\\\/3kubik.com\\\/en\\\/project_category\\\/collaboration\\\/\",\"name\":\"Collaboration Archive - 3kubik GmbH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/3kubik.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/3kubik.com\\\/en\\\/project_category\\\/collaboration\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/3kubik.com\\\/en\\\/project_category\\\/collaboration\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/3kubik.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Collaboration\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/3kubik.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/3kubik.com\\\/en\\\/\",\"name\":\"3kubik GmbH\",\"description\":\"We create workspaces you want to work at\",\"publisher\":{\"@id\":\"https:\\\/\\\/3kubik.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/3kubik.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/3kubik.com\\\/en\\\/#organization\",\"name\":\"3kubik GmbH\",\"url\":\"https:\\\/\\\/3kubik.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/3kubik.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/3kubik.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/3kubik-logo-erweitert.svg\",\"contentUrl\":\"https:\\\/\\\/3kubik.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/3kubik-logo-erweitert.svg\",\"width\":\"1280\",\"height\":\"1024\",\"caption\":\"3kubik GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/3kubik.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/3kubikgmbh\\\/\",\"https:\\\/\\\/www.instagram.com\\\/3kubik_gmbh\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/3kubik-gmbh\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Collaboration Archive - 3kubik GmbH","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Collaboration Archive","og_url":"https:\/\/3kubik.com\/en\/project_category\/collaboration\/","og_site_name":"3kubik GmbH","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/3kubik.com\/en\/project_category\/collaboration\/","url":"https:\/\/3kubik.com\/en\/project_category\/collaboration\/","name":"Collaboration Archive - 3kubik GmbH","isPartOf":{"@id":"https:\/\/3kubik.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/3kubik.com\/en\/project_category\/collaboration\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/3kubik.com\/en\/project_category\/collaboration\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/3kubik.com\/en\/"},{"@type":"ListItem","position":2,"name":"Collaboration"}]},{"@type":"WebSite","@id":"https:\/\/3kubik.com\/en\/#website","url":"https:\/\/3kubik.com\/en\/","name":"3kubik GmbH","description":"We create workspaces you want to work at","publisher":{"@id":"https:\/\/3kubik.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/3kubik.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/3kubik.com\/en\/#organization","name":"3kubik GmbH","url":"https:\/\/3kubik.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/3kubik.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/3kubik.com\/wp-content\/uploads\/2021\/11\/3kubik-logo-erweitert.svg","contentUrl":"https:\/\/3kubik.com\/wp-content\/uploads\/2021\/11\/3kubik-logo-erweitert.svg","width":"1280","height":"1024","caption":"3kubik GmbH"},"image":{"@id":"https:\/\/3kubik.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/3kubikgmbh\/","https:\/\/www.instagram.com\/3kubik_gmbh\/","https:\/\/www.linkedin.com\/company\/3kubik-gmbh"]}]}},"_links":{"self":[{"href":"https:\/\/3kubik.com\/en\/wp-json\/wp\/v2\/project_category\/136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/3kubik.com\/en\/wp-json\/wp\/v2\/project_category"}],"about":[{"href":"https:\/\/3kubik.com\/en\/wp-json\/wp\/v2\/taxonomies\/project_category"}],"wp:post_type":[{"href":"https:\/\/3kubik.com\/en\/wp-json\/wp\/v2\/project?project_category=136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}